{"id":7581,"date":"2022-03-29T15:06:19","date_gmt":"2022-03-29T15:06:19","guid":{"rendered":"https:\/\/www.periodicolapislazuli.com\/noticias\/?p=7581"},"modified":"2022-03-29T15:06:19","modified_gmt":"2022-03-29T15:06:19","slug":"abren-convocatorias-para-las-jornadas-profesionales-de-la-filbo-2022","status":"publish","type":"post","link":"https:\/\/www.periodicolapislazuli.com\/noticias\/abren-convocatorias-para-las-jornadas-profesionales-de-la-filbo-2022\/","title":{"rendered":"Abren convocatorias para las Jornadas Profesionales de la FILBo 2022"},"content":{"rendered":"<p style=\"text-align: right;\"><strong>Bogot\u00e1, febrero del 2022<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7582 size-full\" src=\"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-content\/uploads\/2022\/03\/portada-periodistas.png\" alt=\"\" width=\"1130\" height=\"440\" srcset=\"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-content\/uploads\/2022\/03\/portada-periodistas.png 1130w, https:\/\/www.periodicolapislazuli.com\/noticias\/wp-content\/uploads\/2022\/03\/portada-periodistas-780x304.png 780w, https:\/\/www.periodicolapislazuli.com\/noticias\/wp-content\/uploads\/2022\/03\/portada-periodistas-768x299.png 768w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/p>\n<p style=\"text-align: justify;\">La Feria Internacional del Libro de Bogot\u00e1, que se llevar\u00e1 a cabo de manera presencial en Corferias del 19 de abril al 2 de mayo, lanza las convocatorias para los profesionales del sector del libro que quieran participar en las distintas jornadas de negocios y formaci\u00f3n que en ella ofrece.<\/p>\n<p style=\"text-align: justify;\">Las Jornadas Profesionales de la FILBo son eventos especializados dirigidos a todos los actores de la cadena productiva del libro en Colombia y alrededor del mundo. En ellas se abren espacios de encuentro y oportunidades de negocios entre los actores nacionales e internacionales, as\u00ed como espacios de formaci\u00f3n que responden a las necesidades del sector.<\/p>\n<p style=\"text-align: justify;\">La agenda de cada una de las jornadas requiere inscripci\u00f3n previa. Los formularios y la informaci\u00f3n acerca de cada una de estas actividades, as\u00ed como las fechas de inscripciones, estar\u00e1n disponibles en la p\u00e1gina web de la FILBo <u><a href=\"http:\/\/www.feriadellibro.com\">www.feriadellibro.com<\/a><\/u>.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Sal\u00f3n Internacional de Negocios (27 y 28 de abril en Corferias)<\/strong> es el espacio para la compra y venta de libros, derechos de edici\u00f3n y traducci\u00f3n, y el lugar estrat\u00e9gico para hacer negocios en el primer semestre del a\u00f1o en la regi\u00f3n.<\/li>\n<li><strong>Foros del Libro<\/strong> <strong>(21 y 22 de abril en Corferias)<\/strong> es el espacio de formaci\u00f3n y actualizaci\u00f3n profesional para el sector editorial que convoca a editores, agentes, distribuidores, libreros y estudiantes durante dos d\u00edas, alrededor de charlas y conferencias con expertos de Colombia y el mundo.<\/li>\n<li><strong>Foros de traducci\u00f3n literaria (20 de abril en Corferias)<\/strong> est\u00e1n dirigidos a traductores, editores, profesores, estudiantes e interesados en este campo espec\u00edfico de la traducci\u00f3n.<\/li>\n<li><strong>Libros de pel\u00edcula (29 de abril en Corferias)<\/strong> es el encuentro profesional entre editores, productores y directores audiovisuales con el objetivo de incentivar nuevas relaciones comerciales y oportunidades de negocio para que los libros de autores colombianos sean adaptados a pel\u00edculas o series de televisi\u00f3n, entre otras producciones audiovisuales.<\/li>\n<li><strong>FILBo emprende (25 y 26 de abril en Corferias)<\/strong> es una iniciativa que busca fortalecer emprendimientos de la industria editorial a trav\u00e9s de una agenda de actividades de formaci\u00f3n integral que demuestra las relaciones de la cadena productiva del sector y sus caracter\u00edsticas, al igual que los retos y oportunidades que se presentan dentro de esta. Adicionalmente, los egresados de a\u00f1os anteriores tienen un espacio comercial para divulgar sus publicaciones y proyectos, y as\u00ed poner a prueba lo aprendido en una experiencia que lleva libros directamente a las manos de los lectores.<\/li>\n<li><strong>Clases magistrales de ilustraci\u00f3n (21 y 22 de abril en Corferias)<\/strong> es un programa creado recientemente para la formaci\u00f3n de personas interesadas en conocer m\u00e1s sobre los libros pensados, escritos, ilustrados y editados para ni\u00f1os y j\u00f3venes. En estas dos sesiones, los profesionales en formaci\u00f3n en el campo de la ilustraci\u00f3n tendr\u00e1n un espacio dedicado a la exploraci\u00f3n del lenguaje gr\u00e1fico en sus distintas expresiones. Los inscritos podr\u00e1n perfeccionar su t\u00e9cnica y aprender de dos grandes ilustradores con gran reconocimiento internacional: Hanoch Ernesto Piven y Valeria Gallo.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Informaci\u00f3n <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Manuela Coy <\/strong><\/p>\n<p style=\"text-align: justify;\">Coordinadora de Jornadas Profesionales<\/p>\n<p style=\"text-align: justify;\">Feria Internacional del Libro de Bogot\u00e1<\/p>\n<p style=\"text-align: justify;\">C\u00e1mara Colombiana del Libro<\/p>\n<p style=\"text-align: justify;\"><u><a href=\"mailto:profesionales@camlibro.com.co\">profesionales@camlibro.com.co<\/a><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1, febrero del 2022 La Feria Internacional del Libro de Bogot\u00e1, que se llevar\u00e1 a cabo de manera<\/p>\n","protected":false},"author":3,"featured_media":7582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[2967,213,2970,2969,2968,2810],"class_list":["post-7581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-abiertas","tag-convocatorias","tag-feria-del-libro-de-bogota","tag-filbo-2022","tag-jornadas","tag-profesionales"],"jetpack_featured_media_url":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-content\/uploads\/2022\/03\/portada-periodistas.png","_links":{"self":[{"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/posts\/7581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/comments?post=7581"}],"version-history":[{"count":2,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/posts\/7581\/revisions"}],"predecessor-version":[{"id":7584,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/posts\/7581\/revisions\/7584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/media\/7582"}],"wp:attachment":[{"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/media?parent=7581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/categories?post=7581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.periodicolapislazuli.com\/noticias\/wp-json\/wp\/v2\/tags?post=7581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}